{"id":114103,"date":"2017-11-15T16:49:25","date_gmt":"2017-11-15T15:49:25","guid":{"rendered":"https:\/\/preprod.espaces-atypiques.com\/?post_type=vente&#038;p=114103"},"modified":"2020-08-01T15:55:41","modified_gmt":"2020-08-01T13:55:41","slug":"77240-vert-saint-denis-appartement-en-duplex-avec-terrasse-et-jardin-sm022","status":"publish","type":"vente","link":"https:\/\/www.espaces-atypiques.com\/en\/for-sale\/77240-vert-saint-denis-appartement-en-duplex-avec-terrasse-et-jardin-sm022\/","title":{"rendered":"Appartement en duplex avec terrasse et jardin"},"content":{"rendered":"<p>Dans la commune de Vert Saint Denis, au calme absolu et proche de la for\u00eat, cet appartement agenc\u00e9 en duplex de 90m\u00b2 habitable (67 m2 loi carrez) fait partie d&#8217;une copropri\u00e9t\u00e9 de 3 lots ayant \u00e9t\u00e9 int\u00e9gralement r\u00e9nov\u00e9e en 2010. Son rez de chauss\u00e9e vous accueille avec sa pi\u00e8ce de vie de 20m\u00b2 et sa cuisine semi-ouverte enti\u00e8rement \u00e9quip\u00e9e (12,5m\u00b2). Un escalier vous m\u00e8ne ensuite \u00e0 l&#8217;\u00e9tage d\u00e9di\u00e9 \u00e0 l&#8217;espace nuit. Il se compose d&#8217;une chambre parentale avec dressing, d&#8217;une seconde chambre, d&#8217;une grande salle de bain et d&#8217;un bureau (pouvant servir de chambre d&#8217;enfant ou d&#8217;appoint).\u00a0 Orient\u00e9 Est\/Ouest, cet appartement dispose d&#8217;une petite terrasse, d&#8217;un jardin privatif, d&#8217;un espace potager et de 2 places de stationnement ext\u00e9rieures attenantes au jardin.\u00a0 600euros de charges annuelles (eau et \u00e9clairage parties communes). Tr\u00e8s bon rendement locatif pour un investisseur. Proximit\u00e9 des \u00e9coles et commerces de Vert Saint Denis et Cesson. Acc\u00e8s sur Paris via le RER D (40 mn)\u00a0 Raccordement fibre optique Copropri\u00e9t\u00e9 de 3 lots (Pas de proc\u00e9dure en cours). Charges annuelles : 600 euros.<\/p>\n","protected":false},"author":50,"featured_media":122381,"template":"","meta":{"_acf_changed":false},"criteres":[],"localisations":[513,6489],"statuts-offre":[8194],"types-de-bien":[14],"features":[],"class_list":["post-114103","vente","type-vente","status-publish","has-post-thumbnail","hentry","localisation-77-seine-et-marne","localisation-77240-vert-saint-denis","statut-offre-vendu-en","type-de-bien-apartment"],"acf":{"bien_geolocalisation":{"address":"77240 Vert-Saint-Denis, France","lat":48.5681824,"lng":2.6259136,"zoom":14,"place_id":"ChIJ9fkzRNn65UcR4EeMaMOCCwQ","name":"Vert-Saint-Denis","city":"Vert-Saint-Denis","state":"\u00cele-de-France","state_short":"IDF","country":"France","country_short":"FR"},"annonce_reference":"Seine-et-Marne-SM022","annonce_reference_affaire":"","annonce_num_mandat":"","annonce_date_mise_a_jour":"20200730","agence_nom":"ESPACES ATYPIQUES FONTAINEBLEAU - ESPACES ATYPIQUES FONTAINEBLEAU","agence_nom_court":"Seine-et-Marne","agence_telephone":"01 83 88 97 90","agence_email":"seine.et.marne@espaces-atypiques.com","agence_adresse":"46 rue de France\r\n77300\r\nFONTAINEBLEAU","agence_id":"160925","negociateur_prenom":"Dain\u00e9e","negociateur_nom":"MAURICE","negociateur_telephone":"06 80 98 70 34","negociateur_email":"dainee.maurice@espaces-atypiques.com","negociateur_id":"415900","negociateur_rsac":"","negociateur_ville_rsac":"","negociateur_statut":"","bien_ville":"VERT SAINT DENIS","bien_code_postal":"77240","vente_prix":175000,"vente_honoraires_a_charge":"Vendeur","vente_honoraire_vendeur":8000,"vente_honoraires_acquereur":0,"vente_taxe_fonciere":1000,"vente_copropriete":"Oui","vente_charges_copro":600,"vente_nombre_lots":3,"vente_procedures_copropriete":"Non","bien_sous_titre":"","bien_surface_habitable":90,"bien_surface_carrez":67,"bien_surface_terrain":0,"bien_surface_exterieur":"","bien_nombre_pieces":3,"bien_nombre_chambres":2,"bien_nombre_sdb":1,"bien_nombre_sde":"","bien_balcon":"","bien_terrasse":"","bien_parking":2,"bien_etage":"","bien_etages_immeuble":"","bien_dpe_bareme":[],"bien_annee_reference_prix_energie":null,"bien_dpe_bareme_2024":[],"bien_3annees_reference_prix_energie":"2021, 2022, 2023","bien_dpe_lettre":"E","bien_dpe_valeur":283,"bien_ges_lettre":"C","bien_ges_valeur":15,"bien_min_depenses_energie":"","bien_max_depenses_energie":""},"language":"en","translations":{"en":114103,"fr":122379},"_links":{"self":[{"href":"https:\/\/www.espaces-atypiques.com\/en\/wp-json\/wp\/v2\/ventes\/114103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.espaces-atypiques.com\/en\/wp-json\/wp\/v2\/ventes"}],"about":[{"href":"https:\/\/www.espaces-atypiques.com\/en\/wp-json\/wp\/v2\/types\/vente"}],"author":[{"embeddable":true,"href":"https:\/\/www.espaces-atypiques.com\/en\/wp-json\/wp\/v2\/users\/50"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.espaces-atypiques.com\/en\/wp-json\/wp\/v2\/media\/122381"}],"wp:attachment":[{"href":"https:\/\/www.espaces-atypiques.com\/en\/wp-json\/wp\/v2\/media?parent=114103"}],"wp:term":[{"taxonomy":"hashtag","embeddable":true,"href":"https:\/\/www.espaces-atypiques.com\/en\/wp-json\/wp\/v2\/criteres?post=114103"},{"taxonomy":"localisation","embeddable":true,"href":"https:\/\/www.espaces-atypiques.com\/en\/wp-json\/wp\/v2\/localisations?post=114103"},{"taxonomy":"statut-offre","embeddable":true,"href":"https:\/\/www.espaces-atypiques.com\/en\/wp-json\/wp\/v2\/statuts-offre?post=114103"},{"taxonomy":"type-de-bien","embeddable":true,"href":"https:\/\/www.espaces-atypiques.com\/en\/wp-json\/wp\/v2\/types-de-bien?post=114103"},{"taxonomy":"feature","embeddable":true,"href":"https:\/\/www.espaces-atypiques.com\/en\/wp-json\/wp\/v2\/features?post=114103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}